{"id":10950,"date":"2018-04-23T14:25:23","date_gmt":"2020-07-20T14:29:28","guid":{"rendered":"https:\/\/www.sahm-splice.com\/?post_type=product&#038;p=10950"},"modified":"2025-06-10T14:03:10","modified_gmt":"2025-06-10T12:03:10","slug":"zen-13411-3-pressklemmen-form-c","status":"publish","type":"product","link":"https:\/\/stage.sahm-splice.com\/de\/produkte\/pressklemmen\/aluminium\/zen-13411-3-pressklemmen-form-c\/","title":{"rendered":"ZEN\u00ae 13411-3 Pressklemmen Form C"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Konische Aluminium Pressklemmen nach DIN EN 13411-3 f\u00fcr Anschlagseile nach DIN EN 13414-1.<\/p>\n<ul class=\"uk-list uk-list-bullet\">\n<li>F\u00fcr Drahtseile mit einer max. Nennfestigkeit von 1960 N\/mm<sup>2<\/sup><\/li>\n<li>Geeignet f\u00fcr Stahldrahtseile nach EN 12385-4<\/li>\n<li>Gefertigt aus nahtlosen Rohren gem. DIN EN 13411-3<\/li>\n<li>Durch die Kontrollbohrung ist das Totseilende nach der Verpressung sichtbar<\/li>\n<li>Verpresster konischer Teil der Klemme verhindert das Verhaken an Hindernissen<\/li>\n<li>Lieferbar in den Gr\u00f6\u00dfen 8 \u2013 52<\/li>\n<li>Verarbeitung mit unseren <a href=\"https:\/\/www.sahm-splice.com\/de\/produkte\/werkzeuge-zubehoer\/pressbacken\/universal\/\">Pressbacken &#8222;Universal&#8220;<\/a> mit Schneidekanten<\/li>\n<\/ul>\n","protected":false},"featured_media":12997,"template":"","meta":{"wds_primary_product_brand":0,"wds_primary_product_cat":308},"product_brand":[],"product_cat":[308],"product_tag":[],"class_list":{"0":"post-10950","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aluminium","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/product\/10950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/media\/12997"}],"wp:attachment":[{"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/media?parent=10950"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/product_brand?post=10950"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/product_cat?post=10950"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stage.sahm-splice.com\/de\/wp-json\/wp\/v2\/product_tag?post=10950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}